{"id":3204,"date":"2025-11-11T15:30:25","date_gmt":"2025-11-11T15:30:25","guid":{"rendered":"https:\/\/gymdesign.ca\/employees\/"},"modified":"2025-11-11T15:30:25","modified_gmt":"2025-11-11T15:30:25","slug":"employees","status":"publish","type":"page","link":"https:\/\/gymdesign.ca\/en\/employees\/","title":{"rendered":"Employees"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-3204","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Employees - Gym Design<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gymdesign.ca\/en\/employees\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Employees - Gym Design\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gymdesign.ca\/en\/employees\/\" \/>\n<meta property=\"og:site_name\" content=\"Gym Design\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gymdesign.ca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gymdesign.ca\\\/en\\\/employees\\\/\",\"url\":\"https:\\\/\\\/gymdesign.ca\\\/en\\\/employees\\\/\",\"name\":\"Employees - Gym Design\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gymdesign.ca\\\/en\\\/#website\"},\"datePublished\":\"2025-11-11T15:30:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gymdesign.ca\\\/en\\\/employees\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gymdesign.ca\\\/en\\\/employees\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gymdesign.ca\\\/en\\\/employees\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/gymdesign.ca\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Employees\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gymdesign.ca\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/gymdesign.ca\\\/en\\\/\",\"name\":\"Gym Design\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/gymdesign.ca\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gymdesign.ca\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gymdesign.ca\\\/en\\\/#organization\",\"name\":\"Gym Design\",\"url\":\"https:\\\/\\\/gymdesign.ca\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gymdesign.ca\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gymdesign.ca\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-GymDesign_Logo_VFSEPT17-07-scaled.png\",\"contentUrl\":\"https:\\\/\\\/gymdesign.ca\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-GymDesign_Logo_VFSEPT17-07-scaled.png\",\"width\":4799,\"height\":1909,\"caption\":\"Gym Design\"},\"image\":{\"@id\":\"https:\\\/\\\/gymdesign.ca\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/gymdesign.ca\",\"https:\\\/\\\/www.instagram.com\\\/gymdesign.ca\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/gym-design-creations\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Employees - Gym Design","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gymdesign.ca\/en\/employees\/","og_locale":"en_US","og_type":"article","og_title":"Employees - Gym Design","og_url":"https:\/\/gymdesign.ca\/en\/employees\/","og_site_name":"Gym Design","article_publisher":"https:\/\/www.facebook.com\/gymdesign.ca","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gymdesign.ca\/en\/employees\/","url":"https:\/\/gymdesign.ca\/en\/employees\/","name":"Employees - Gym Design","isPartOf":{"@id":"https:\/\/gymdesign.ca\/en\/#website"},"datePublished":"2025-11-11T15:30:25+00:00","breadcrumb":{"@id":"https:\/\/gymdesign.ca\/en\/employees\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gymdesign.ca\/en\/employees\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gymdesign.ca\/en\/employees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/gymdesign.ca\/en\/"},{"@type":"ListItem","position":2,"name":"Employees"}]},{"@type":"WebSite","@id":"https:\/\/gymdesign.ca\/en\/#website","url":"https:\/\/gymdesign.ca\/en\/","name":"Gym Design","description":"","publisher":{"@id":"https:\/\/gymdesign.ca\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gymdesign.ca\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/gymdesign.ca\/en\/#organization","name":"Gym Design","url":"https:\/\/gymdesign.ca\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gymdesign.ca\/en\/#\/schema\/logo\/image\/","url":"https:\/\/gymdesign.ca\/wp-content\/uploads\/2024\/03\/cropped-GymDesign_Logo_VFSEPT17-07-scaled.png","contentUrl":"https:\/\/gymdesign.ca\/wp-content\/uploads\/2024\/03\/cropped-GymDesign_Logo_VFSEPT17-07-scaled.png","width":4799,"height":1909,"caption":"Gym Design"},"image":{"@id":"https:\/\/gymdesign.ca\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gymdesign.ca","https:\/\/www.instagram.com\/gymdesign.ca\/","https:\/\/www.linkedin.com\/company\/gym-design-creations\/"]}]}},"_links":{"self":[{"href":"https:\/\/gymdesign.ca\/en\/wp-json\/wp\/v2\/pages\/3204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gymdesign.ca\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gymdesign.ca\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gymdesign.ca\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/gymdesign.ca\/en\/wp-json\/wp\/v2\/comments?post=3204"}],"version-history":[{"count":0,"href":"https:\/\/gymdesign.ca\/en\/wp-json\/wp\/v2\/pages\/3204\/revisions"}],"wp:attachment":[{"href":"https:\/\/gymdesign.ca\/en\/wp-json\/wp\/v2\/media?parent=3204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}